{"id":1871,"date":"2026-06-27T10:19:08","date_gmt":"2026-06-27T07:19:08","guid":{"rendered":"https:\/\/www.pirula.fi\/?page_id=1871"},"modified":"2026-06-27T10:19:49","modified_gmt":"2026-06-27T07:19:49","slug":"viinit","status":"publish","type":"page","link":"https:\/\/www.pirula.fi\/en\/tuotteet\/viinit\/","title":{"rendered":"Viinit"},"content":{"rendered":"<style>.kb-row-layout-id1871_6db60c-9f > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1871_6db60c-9f > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1871_6db60c-9f > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:160px;padding-right:20px;padding-bottom:120px;padding-left:20px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1871_6db60c-9f{background-image:url('https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2023\/06\/Pirulan-kyltti.jpg');background-size:cover;background-position:54% 62%;background-attachment:fixed;background-repeat:no-repeat;}.kb-row-layout-id1871_6db60c-9f > .kt-row-layout-overlay{opacity:0.35;background-color:var(--global-palette9, #ffffff);}@media all and (max-width: 1024px), only screen and (min-device-width: 1024px) and (max-device-width: 1366px) and (-webkit-min-device-pixel-ratio: 2) and (hover: none){.kb-row-layout-id1871_6db60c-9f{background-attachment:scroll;}}@media all and (max-width: 1024px){.kb-row-layout-id1871_6db60c-9f > .kt-row-column-wrap{padding-top:80px;padding-bottom:80px;grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1871_6db60c-9f > .kt-row-column-wrap{padding-top:60px;padding-bottom:60px;grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1871_6db60c-9f alignnone kt-row-has-bg kt-jarallax wp-block-kadence-rowlayout\" data-img-position=\"54% 62%\" data-img-size=\"cover\"><div class=\"kt-row-layout-overlay kt-row-overlay-normal\"><\/div><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1871_eddf6c-41 > .kt-inside-inner-col,.kadence-column1871_eddf6c-41 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_eddf6c-41 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_eddf6c-41 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_eddf6c-41 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_eddf6c-41 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_eddf6c-41{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_eddf6c-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_eddf6c-41 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_eddf6c-41 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id1871_b2699d-e1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1871_b2699d-e1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1871_b2699d-e1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:600px;margin-left:auto;margin-right:auto;padding-top:190px;padding-bottom:0px;grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1871_b2699d-e1 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1871_b2699d-e1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1871_b2699d-e1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1871_b2699d-e1 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1871_ccde79-71 > .kt-inside-inner-col,.kadence-column1871_ccde79-71 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_ccde79-71 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_ccde79-71 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_ccde79-71 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_ccde79-71 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_ccde79-71{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_ccde79-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_ccde79-71 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_ccde79-71 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1871_2b80ae-7f, .wp-block-kadence-advancedheading.kt-adv-heading1871_2b80ae-7f[data-kb-block=\"kb-adv-heading1871_2b80ae-7f\"]{margin-bottom:10px;text-align:center;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1871_2b80ae-7f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1871_2b80ae-7f[data-kb-block=\"kb-adv-heading1871_2b80ae-7f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1871_2b80ae-7f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1871_2b80ae-7f[data-kb-block=\"kb-adv-heading1871_2b80ae-7f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h1 class=\"kt-adv-heading1871_2b80ae-7f wp-block-kadence-advancedheading has-theme-palette-7-color has-text-color\" data-kb-block=\"kb-adv-heading1871_2b80ae-7f\">Viinit<\/h1>\n<\/div><\/div>\n\n<\/div><\/div><\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1871_79d582-57 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1871_79d582-57 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1871_79d582-57 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);padding-top:var(--global-kb-spacing-lg, 3rem);padding-bottom:var(--global-kb-spacing-md, 2rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1871_79d582-57 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1871_79d582-57 > .kt-row-column-wrap{padding-top:var(--global-kb-spacing-xs, 1rem);grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1871_79d582-57 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1871_79d582-57 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top\">\n<style>.kadence-column1871_903476-0c > .kt-inside-inner-col,.kadence-column1871_903476-0c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_903476-0c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_903476-0c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_903476-0c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_903476-0c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_903476-0c{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_903476-0c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_903476-0c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_903476-0c\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56, .wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56[data-kb-block=\"kb-adv-heading1871_c428c4-56\"]{text-align:center;font-style:normal;text-transform:none;}.wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56[data-kb-block=\"kb-adv-heading1871_c428c4-56\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56[data-kb-block=\"kb-adv-heading1871_c428c4-56\"] img.kb-inline-image{width:150px;vertical-align:baseline;}@media all and (max-width: 1024px){.wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56, .wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56[data-kb-block=\"kb-adv-heading1871_c428c4-56\"]{margin-bottom:0px;text-align:center!important;}}@media all and (max-width: 767px){.wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56, .wp-block-kadence-advancedheading.kt-adv-heading1871_c428c4-56[data-kb-block=\"kb-adv-heading1871_c428c4-56\"]{text-align:center!important;}}<\/style>\n<h2 class=\"kt-adv-heading1871_c428c4-56 wp-block-kadence-advancedheading\" data-kb-block=\"kb-adv-heading1871_c428c4-56\">Pirulan viinit<\/h2>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.kb-row-layout-id1871_b1f18f-b1 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1871_b1f18f-b1 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1871_b1f18f-b1 > .kt-row-column-wrap{column-gap:var(--global-kb-gap-md, 2rem);row-gap:var(--global-kb-gap-md, 2rem);max-width:var( --global-content-width, 1290px );padding-left:var(--global-content-edge-padding);padding-right:var(--global-content-edge-padding);padding-top:var(--global-kb-spacing-xxl, 5rem);padding-bottom:var(--global-kb-spacing-xxl, 5rem);grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1871_b1f18f-b1 > .kt-row-layout-overlay{opacity:0.44;mix-blend-mode:multiply;}@media all and (max-width: 1024px){.kb-row-layout-id1871_b1f18f-b1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}@media all and (max-width: 767px){.kb-row-layout-id1871_b1f18f-b1 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}.kb-row-layout-id1871_b1f18f-b1 .rotate-text {  transform-origin: 0 0;    transform: rotate(-90deg);    position: absolute;    width: 350px !important;    bottom: 0;    margin-left: 20px;}.kb-row-layout-id1871_b1f18f-b1 .rotate-text-container {  position: relative;}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1871_b1f18f-b1 alignfull has-theme-palette8-background-color kt-row-has-bg wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-1-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kb-theme-content-width\">\n<style>.kadence-column1871_8a7cfc-dc > .kt-inside-inner-col,.kadence-column1871_8a7cfc-dc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_8a7cfc-dc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_8a7cfc-dc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_8a7cfc-dc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_8a7cfc-dc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_8a7cfc-dc{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_8a7cfc-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_8a7cfc-dc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_8a7cfc-dc inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.kb-row-layout-id1871_9e8e8e-c9 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1871_9e8e8e-c9 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1871_9e8e8e-c9 > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1400px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1871_9e8e8e-c9 > .kt-row-layout-overlay{opacity:0.30;}.kb-row-layout-id1871_9e8e8e-c9 .kt-row-layout-bottom-sep{height:100px;}.kb-row-layout-id1871_9e8e8e-c9 .kt-row-layout-bottom-sep svg{width:100%;}.kb-row-layout-id1871_9e8e8e-c9 .kt-row-layout-bottom-sep svg{fill:var(--global-palette2, #2B6CB0)!important;}@media all and (max-width: 1024px){.kb-row-layout-id1871_9e8e8e-c9 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 1024px){.kb-row-layout-id1871_9e8e8e-c9 .kt-row-layout-bottom-sep{height:px;}}@media all and (max-width: 1024px){.kb-row-layout-id1871_9e8e8e-c9 .kt-row-layout-bottom-sep svg{width:%;}}@media all and (max-width: 767px){.kb-row-layout-id1871_9e8e8e-c9 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}.kb-row-layout-id1871_9e8e8e-c9 .kt-row-layout-bottom-sep{height:px;}.kb-row-layout-id1871_9e8e8e-c9 .kt-row-layout-bottom-sep svg{width:%;}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1871_9e8e8e-c9 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column1871_e25fc5-2f > .kt-inside-inner-col{display:flex;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col,.kadence-column1871_e25fc5-2f > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col{column-gap:0px;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-end;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col > *, .kadence-column1871_e25fc5-2f > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_e25fc5-2f > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column1871_e25fc5-2f{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e25fc5-2f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e25fc5-2f > .kt-inside-inner-col{align-items:flex-end;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_e25fc5-2f{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1871_e25fc5-2f{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e25fc5-2f{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e25fc5-2f > .kt-inside-inner-col{align-items:flex-end;}}@media all and (max-width: 1024px){.kadence-column1871_e25fc5-2f > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-end;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1871_e25fc5-2f > .kt-inside-inner-col > *, .kadence-column1871_e25fc5-2f > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_e25fc5-2f > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1871_e25fc5-2f{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e25fc5-2f{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e25fc5-2f > .kt-inside-inner-col{align-items:flex-end;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col > *, .kadence-column1871_e25fc5-2f > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_e25fc5-2f > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_e25fc5-2f > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_e25fc5-2f kb-section-dir-horizontal inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1871_77ca5e-bc{max-width:60px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column1871_77ca5e-bc{-webkit-flex:0 1 60px;flex:0 1 60px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column1871_77ca5e-bc > .kt-inside-inner-col,.kadence-column1871_77ca5e-bc > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_77ca5e-bc > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_77ca5e-bc > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_77ca5e-bc > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_77ca5e-bc > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_77ca5e-bc{position:relative;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column1871_77ca5e-bc{-webkit-flex:0 1 60px;flex:0 1 60px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kadence-column1871_77ca5e-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column1871_77ca5e-bc{max-width:60px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column1871_77ca5e-bc > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_77ca5e-bc rotate-text-container\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1871_ad507c-9f, .wp-block-kadence-advancedheading.kt-adv-heading1871_ad507c-9f[data-kb-block=\"kb-adv-heading1871_ad507c-9f\"]{text-align:left;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1871_ad507c-9f mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1871_ad507c-9f[data-kb-block=\"kb-adv-heading1871_ad507c-9f\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1871_ad507c-9f img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1871_ad507c-9f[data-kb-block=\"kb-adv-heading1871_ad507c-9f\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading1871_ad507c-9f rotate-text wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1871_ad507c-9f\">Pirulan punainen<\/h6>\n<\/div><\/div>\n\n\n<style>.kadence-column1871_3fcc42-63 > .kt-inside-inner-col{display:flex;}.kadence-column1871_3fcc42-63 > .kt-inside-inner-col,.kadence-column1871_3fcc42-63 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_3fcc42-63 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_3fcc42-63 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_3fcc42-63 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_3fcc42-63 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_3fcc42-63{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_3fcc42-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_3fcc42-63 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_3fcc42-63 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1871_9e1320-86:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image1871_9e1320-86 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image1871_9e1320-86 img.kb-img, .kb-image1871_9e1320-86 .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;object-position:50% 85%;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1871_9e1320-86 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port34\"><img decoding=\"async\" width=\"1001\" height=\"1500\" data-src=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PUNAINEN_viini.jpg\" class=\"kb-img wp-image-1837 lazyload\" data-srcset=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PUNAINEN_viini.jpg 1001w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PUNAINEN_viini-200x300.jpg 200w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PUNAINEN_viini-683x1024.jpg 683w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PUNAINEN_viini-768x1151.jpg 768w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PUNAINEN_viini-8x12.jpg 8w\" data-sizes=\"(max-width: 1001px) 100vw, 1001px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1001px; --smush-placeholder-aspect-ratio: 1001\/1500;\" \/><\/div><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1871_91483f-08 > .kt-inside-inner-col,.kadence-column1871_91483f-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_91483f-08 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_91483f-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_91483f-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_91483f-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_91483f-08{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_91483f-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_91483f-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_91483f-08\"><div class=\"kt-inside-inner-col\">\n<h3 class=\"wp-block-heading\"><strong>Pirula Punainen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Keskit\u00e4ytel\u00e4inen, runsaan mustaherukkainen, kevyen ruusunmarjainen, hennon mustikkainen, herukanlehtinen.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Alkoholia 10,5\u202f%, 0,75 l<br><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1871_82a9f2-78 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1871_82a9f2-78 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1871_82a9f2-78\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id1871_8f5aec-d2 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1871_8f5aec-d2 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1871_8f5aec-d2 > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1400px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1871_8f5aec-d2{border-bottom-right-radius:3px;isolation:isolate;}.kb-row-layout-id1871_8f5aec-d2 > .kt-row-layout-overlay{border-bottom-right-radius:3px;}.kb-row-layout-id1871_8f5aec-d2 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1871_8f5aec-d2 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1871_8f5aec-d2 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1871_8f5aec-d2 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column1871_1fd18e-17 > .kt-inside-inner-col{display:flex;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col,.kadence-column1871_1fd18e-17 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col{column-gap:0px;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-end;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col > *, .kadence-column1871_1fd18e-17 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_1fd18e-17 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column1871_1fd18e-17{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_1fd18e-17{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_1fd18e-17 > .kt-inside-inner-col{align-items:flex-end;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_1fd18e-17{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1871_1fd18e-17{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_1fd18e-17{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_1fd18e-17 > .kt-inside-inner-col{align-items:flex-end;}}@media all and (max-width: 1024px){.kadence-column1871_1fd18e-17 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-end;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1871_1fd18e-17 > .kt-inside-inner-col > *, .kadence-column1871_1fd18e-17 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_1fd18e-17 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1871_1fd18e-17{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_1fd18e-17{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_1fd18e-17 > .kt-inside-inner-col{align-items:flex-end;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col > *, .kadence-column1871_1fd18e-17 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_1fd18e-17 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_1fd18e-17 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_1fd18e-17 kb-section-dir-horizontal inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1871_c4a893-0e{max-width:60px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column1871_c4a893-0e{-webkit-flex:0 1 60px;flex:0 1 60px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column1871_c4a893-0e > .kt-inside-inner-col,.kadence-column1871_c4a893-0e > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_c4a893-0e > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_c4a893-0e > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_c4a893-0e > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_c4a893-0e > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_c4a893-0e{position:relative;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column1871_c4a893-0e{-webkit-flex:0 1 60px;flex:0 1 60px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kadence-column1871_c4a893-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column1871_c4a893-0e{max-width:60px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column1871_c4a893-0e > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_c4a893-0e rotate-text-container\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1871_360c5c-b9, .wp-block-kadence-advancedheading.kt-adv-heading1871_360c5c-b9[data-kb-block=\"kb-adv-heading1871_360c5c-b9\"]{text-align:left;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1871_360c5c-b9 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1871_360c5c-b9[data-kb-block=\"kb-adv-heading1871_360c5c-b9\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1871_360c5c-b9 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1871_360c5c-b9[data-kb-block=\"kb-adv-heading1871_360c5c-b9\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading1871_360c5c-b9 rotate-text wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1871_360c5c-b9\">Pirityinen<\/h6>\n<\/div><\/div>\n\n\n<style>.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col{display:flex;}.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col,.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_8e8ca3-94{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_8e8ca3-94 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_8e8ca3-94 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1871_6902d9-90:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image1871_6902d9-90 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image1871_6902d9-90 img.kb-img, .kb-image1871_6902d9-90 .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;object-position:49% 88%;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1871_6902d9-90 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port34\"><img decoding=\"async\" width=\"1001\" height=\"1500\" data-src=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PIRITYINEN_viini.jpg\" class=\"kb-img wp-image-1836 lazyload\" data-srcset=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PIRITYINEN_viini.jpg 1001w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PIRITYINEN_viini-200x300.jpg 200w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PIRITYINEN_viini-683x1024.jpg 683w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PIRITYINEN_viini-768x1151.jpg 768w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_PIRITYINEN_viini-8x12.jpg 8w\" data-sizes=\"(max-width: 1001px) 100vw, 1001px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1001px; --smush-placeholder-aspect-ratio: 1001\/1500;\" \/><\/div><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1871_8cb690-8b > .kt-inside-inner-col,.kadence-column1871_8cb690-8b > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_8cb690-8b > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_8cb690-8b > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_8cb690-8b > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_8cb690-8b > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_8cb690-8b{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_8cb690-8b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_8cb690-8b > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_8cb690-8b\"><div class=\"kt-inside-inner-col\">\n<h3 class=\"wp-block-heading\"><strong>Pirityinen<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Kuiva, hapokas, valkoherukkainen, sitruksinen, karviaismainen, hennon ginimausteinen.<br><br>Alkoholia 11,0\u202f%, 0,75\u202fl<br><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1871_e78c6b-ef .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1871_e78c6b-ef .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1871_e78c6b-ef\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id1871_709dd6-5a > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1871_709dd6-5a > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1871_709dd6-5a > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1400px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1871_709dd6-5a{border-bottom-right-radius:3px;isolation:isolate;}.kb-row-layout-id1871_709dd6-5a > .kt-row-layout-overlay{border-bottom-right-radius:3px;}.kb-row-layout-id1871_709dd6-5a > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1871_709dd6-5a > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1871_709dd6-5a > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1871_709dd6-5a alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col{display:flex;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col,.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col{column-gap:0px;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-end;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > *, .kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column1871_a6e8b7-97{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_a6e8b7-97{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col{align-items:flex-end;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_a6e8b7-97{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1871_a6e8b7-97{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_a6e8b7-97{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col{align-items:flex-end;}}@media all and (max-width: 1024px){.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-end;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > *, .kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1871_a6e8b7-97{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_a6e8b7-97{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col{align-items:flex-end;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > *, .kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_a6e8b7-97 > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_a6e8b7-97 kb-section-dir-horizontal inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1871_8c7425-1c{max-width:60px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column1871_8c7425-1c{-webkit-flex:0 1 60px;flex:0 1 60px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column1871_8c7425-1c > .kt-inside-inner-col,.kadence-column1871_8c7425-1c > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_8c7425-1c > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_8c7425-1c > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_8c7425-1c > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_8c7425-1c > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_8c7425-1c{position:relative;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column1871_8c7425-1c{-webkit-flex:0 1 60px;flex:0 1 60px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kadence-column1871_8c7425-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column1871_8c7425-1c{max-width:60px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column1871_8c7425-1c > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_8c7425-1c rotate-text-container\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1871_769763-93, .wp-block-kadence-advancedheading.kt-adv-heading1871_769763-93[data-kb-block=\"kb-adv-heading1871_769763-93\"]{text-align:left;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1871_769763-93 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1871_769763-93[data-kb-block=\"kb-adv-heading1871_769763-93\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1871_769763-93 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1871_769763-93[data-kb-block=\"kb-adv-heading1871_769763-93\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading1871_769763-93 rotate-text wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1871_769763-93\">Pirulan Rose<\/h6>\n<\/div><\/div>\n\n\n<style>.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col{display:flex;}.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col,.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_cedc8f-c9{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_cedc8f-c9 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_cedc8f-c9 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1871_886f87-b8:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image1871_886f87-b8 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image1871_886f87-b8 img.kb-img, .kb-image1871_886f87-b8 .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;object-position:51% 88%;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1871_886f87-b8 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port34\"><img decoding=\"async\" width=\"1001\" height=\"1500\" data-src=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirula_Rose_viini.jpg\" class=\"kb-img wp-image-1835 lazyload\" data-srcset=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirula_Rose_viini.jpg 1001w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirula_Rose_viini-200x300.jpg 200w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirula_Rose_viini-683x1024.jpg 683w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirula_Rose_viini-768x1151.jpg 768w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirula_Rose_viini-8x12.jpg 8w\" data-sizes=\"(max-width: 1001px) 100vw, 1001px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1001px; --smush-placeholder-aspect-ratio: 1001\/1500;\" \/><\/div><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1871_7fd957-39 > .kt-inside-inner-col,.kadence-column1871_7fd957-39 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_7fd957-39 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_7fd957-39 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_7fd957-39 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_7fd957-39 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_7fd957-39{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_7fd957-39 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_7fd957-39 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_7fd957-39\"><div class=\"kt-inside-inner-col\">\n<h3 class=\"wp-block-heading\"><strong>Pirulan Rose<\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Vaalean punainen, puolimakea, kyps\u00e4n valkoherukkainen, kevyen ruusunmarjainen, hennon mustaherukkainen, herukanlehtinen.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br>Alkoholia 10,0 %, 0,75 l<br><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1871_67f43c-62 .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1871_67f43c-62 .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1871_67f43c-62\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n\n\n<style>.kb-row-layout-id1871_f44735-e7 > .kt-row-column-wrap{align-content:start;}:where(.kb-row-layout-id1871_f44735-e7 > .kt-row-column-wrap) > .wp-block-kadence-column{justify-content:start;}.kb-row-layout-id1871_f44735-e7 > .kt-row-column-wrap{column-gap:80px;row-gap:var(--global-kb-gap-md, 2rem);max-width:1400px;margin-left:auto;margin-right:auto;padding-top:var(--global-kb-spacing-sm, 1.5rem);padding-bottom:var(--global-kb-spacing-sm, 1.5rem);grid-template-columns:repeat(2, minmax(0, 1fr));}.kb-row-layout-id1871_f44735-e7{border-bottom-right-radius:3px;isolation:isolate;}.kb-row-layout-id1871_f44735-e7 > .kt-row-layout-overlay{border-bottom-right-radius:3px;}.kb-row-layout-id1871_f44735-e7 > .kt-row-layout-overlay{opacity:0.30;}@media all and (max-width: 1024px){.kb-row-layout-id1871_f44735-e7 > .kt-row-column-wrap{grid-template-columns:repeat(2, minmax(0, 1fr));}}@media all and (max-width: 767px){.kb-row-layout-id1871_f44735-e7 > .kt-row-column-wrap{grid-template-columns:minmax(0, 1fr);}}<\/style><div class=\"kb-row-layout-wrap kb-row-layout-id1871_f44735-e7 alignnone wp-block-kadence-rowlayout\"><div class=\"kt-row-column-wrap kt-has-2-columns kt-row-layout-equal kt-tab-layout-inherit kt-mobile-layout-row kt-row-valign-top kt-inner-column-height-full\">\n<style>.kadence-column1871_e3372e-8a > .kt-inside-inner-col{display:flex;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col,.kadence-column1871_e3372e-8a > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col{column-gap:0px;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-end;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col > *, .kadence-column1871_e3372e-8a > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_e3372e-8a > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}.kt-row-column-wrap > .kadence-column1871_e3372e-8a{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e3372e-8a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e3372e-8a > .kt-inside-inner-col{align-items:flex-end;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_e3372e-8a{position:relative;}@media all and (max-width: 1024px){.kt-row-column-wrap > .kadence-column1871_e3372e-8a{align-self:flex-end;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e3372e-8a{align-self:auto;}}@media all and (max-width: 1024px){.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e3372e-8a > .kt-inside-inner-col{align-items:flex-end;}}@media all and (max-width: 1024px){.kadence-column1871_e3372e-8a > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;align-items:flex-end;}}@media all and (min-width: 768px) and (max-width: 1024px){.kadence-column1871_e3372e-8a > .kt-inside-inner-col > *, .kadence-column1871_e3372e-8a > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_e3372e-8a > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}@media all and (max-width: 767px){.kt-row-column-wrap > .kadence-column1871_e3372e-8a{align-self:flex-end;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e3372e-8a{align-self:auto;}.kt-inner-column-height-full:not(.kt-has-1-columns) > .wp-block-kadence-column.kadence-column1871_e3372e-8a > .kt-inside-inner-col{align-items:flex-end;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col{flex-direction:row;flex-wrap:wrap;justify-content:flex-start;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col > *, .kadence-column1871_e3372e-8a > .kt-inside-inner-col > figure.wp-block-image, .kadence-column1871_e3372e-8a > .kt-inside-inner-col > figure.wp-block-kadence-image{margin-top:0px;margin-bottom:0px;}.kadence-column1871_e3372e-8a > .kt-inside-inner-col > .kb-image-is-ratio-size{flex-grow:1;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_e3372e-8a kb-section-dir-horizontal inner-column-2\"><div class=\"kt-inside-inner-col\"><style>.kadence-column1871_2fa40c-11{max-width:60px;margin-left:auto;margin-right:auto;}.wp-block-kadence-column.kb-section-dir-horizontal:not(.kb-section-md-dir-vertical)>.kt-inside-inner-col>.kadence-column1871_2fa40c-11{-webkit-flex:0 1 60px;flex:0 1 60px;max-width:unset;margin-left:unset;margin-right:unset;}.kadence-column1871_2fa40c-11 > .kt-inside-inner-col,.kadence-column1871_2fa40c-11 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_2fa40c-11 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_2fa40c-11 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_2fa40c-11 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_2fa40c-11 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_2fa40c-11{position:relative;}@media all and (min-width: 1025px){.wp-block-kadence-column.kb-section-dir-horizontal>.kt-inside-inner-col>.kadence-column1871_2fa40c-11{-webkit-flex:0 1 60px;flex:0 1 60px;max-width:unset;margin-left:unset;margin-right:unset;}}@media all and (max-width: 1024px){.kadence-column1871_2fa40c-11 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.wp-block-kadence-column.kb-section-sm-dir-vertical:not(.kb-section-sm-dir-horizontal):not(.kb-section-sm-dir-specificity)>.kt-inside-inner-col>.kadence-column1871_2fa40c-11{max-width:60px;-webkit-flex:1;flex:1;margin-left:auto;margin-right:auto;}.kadence-column1871_2fa40c-11 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_2fa40c-11 rotate-text-container\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-advancedheading.kt-adv-heading1871_456918-22, .wp-block-kadence-advancedheading.kt-adv-heading1871_456918-22[data-kb-block=\"kb-adv-heading1871_456918-22\"]{text-align:left;font-weight:700;font-style:normal;}.wp-block-kadence-advancedheading.kt-adv-heading1871_456918-22 mark.kt-highlight, .wp-block-kadence-advancedheading.kt-adv-heading1871_456918-22[data-kb-block=\"kb-adv-heading1871_456918-22\"] mark.kt-highlight{font-style:normal;color:#f76a0c;-webkit-box-decoration-break:clone;box-decoration-break:clone;padding-top:0px;padding-right:0px;padding-bottom:0px;padding-left:0px;}.wp-block-kadence-advancedheading.kt-adv-heading1871_456918-22 img.kb-inline-image, .wp-block-kadence-advancedheading.kt-adv-heading1871_456918-22[data-kb-block=\"kb-adv-heading1871_456918-22\"] img.kb-inline-image{width:150px;vertical-align:baseline;}<\/style>\n<h6 class=\"kt-adv-heading1871_456918-22 rotate-text wp-block-kadence-advancedheading has-theme-palette-3-color has-text-color\" data-kb-block=\"kb-adv-heading1871_456918-22\">Pirula valkoinen<\/h6>\n<\/div><\/div>\n\n\n<style>.kadence-column1871_6af578-08 > .kt-inside-inner-col{display:flex;}.kadence-column1871_6af578-08 > .kt-inside-inner-col,.kadence-column1871_6af578-08 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_6af578-08 > .kt-inside-inner-col{row-gap:var(--global-kb-gap-none, 0rem );column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_6af578-08 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_6af578-08 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_6af578-08 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_6af578-08{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_6af578-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_6af578-08 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_6af578-08 inner-column-1\"><div class=\"kt-inside-inner-col\"><style>.wp-block-kadence-image.kb-image1871_90f659-46:not(.kb-specificity-added):not(.kb-extra-specificity-added){margin-bottom:0px;}.kb-image1871_90f659-46 .kb-image-has-overlay:after{opacity:0.3;border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kb-image1871_90f659-46 img.kb-img, .kb-image1871_90f659-46 .kb-img img{border-top-left-radius:10px;border-top-right-radius:10px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;object-position:53% 88%;}<\/style>\n<figure class=\"wp-block-kadence-image kb-image1871_90f659-46 kb-image-is-ratio-size\"><div class=\"kb-is-ratio-image kb-image-ratio-port34\"><img decoding=\"async\" width=\"1001\" height=\"1500\" data-src=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_VALKOINEN_viini.jpg\" class=\"kb-img wp-image-1838 lazyload\" data-srcset=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_VALKOINEN_viini.jpg 1001w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_VALKOINEN_viini-200x300.jpg 200w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_VALKOINEN_viini-683x1024.jpg 683w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_VALKOINEN_viini-768x1151.jpg 768w, https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/Pirulan_VALKOINEN_viini-8x12.jpg 8w\" data-sizes=\"(max-width: 1001px) 100vw, 1001px\" src=\"data:image\/svg+xml;base64,PHN2ZyB3aWR0aD0iMSIgaGVpZ2h0PSIxIiB4bWxucz0iaHR0cDovL3d3dy53My5vcmcvMjAwMC9zdmciPjwvc3ZnPg==\" style=\"--smush-placeholder-width: 1001px; --smush-placeholder-aspect-ratio: 1001\/1500;\" \/><\/div><\/figure>\n<\/div><\/div>\n<\/div><\/div>\n\n\n<style>.kadence-column1871_10e483-e1 > .kt-inside-inner-col,.kadence-column1871_10e483-e1 > .kt-inside-inner-col:before{border-top-left-radius:0px;border-top-right-radius:0px;border-bottom-right-radius:0px;border-bottom-left-radius:0px;}.kadence-column1871_10e483-e1 > .kt-inside-inner-col{column-gap:var(--global-kb-gap-sm, 1rem);}.kadence-column1871_10e483-e1 > .kt-inside-inner-col{flex-direction:column;}.kadence-column1871_10e483-e1 > .kt-inside-inner-col > .aligncenter{width:100%;}.kadence-column1871_10e483-e1 > .kt-inside-inner-col:before{opacity:0.3;}.kadence-column1871_10e483-e1{position:relative;}@media all and (max-width: 1024px){.kadence-column1871_10e483-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}@media all and (max-width: 767px){.kadence-column1871_10e483-e1 > .kt-inside-inner-col{flex-direction:column;justify-content:center;}}<\/style>\n<div class=\"wp-block-kadence-column kadence-column1871_10e483-e1\"><div class=\"kt-inside-inner-col\">\n<h3 class=\"wp-block-heading\"><strong>Pirulan <strong>Valkoinen<\/strong><\/strong><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\">Kullankeltainen, puolikuiva, hapokas, kyps\u00e4n valkoherukkainen. <br><br><br>Alkoholia 9,5 %, 0,75 l<br><\/p>\n<\/div><\/div>\n\n<\/div><\/div>\n\n<style>.wp-block-kadence-spacer.kt-block-spacer-1871_8e3e11-7e .kt-block-spacer{height:30px;}.wp-block-kadence-spacer.kt-block-spacer-1871_8e3e11-7e .kt-divider{border-top-width:1px;height:1px;border-top-color:#eee;width:80%;border-top-style:solid;}<\/style>\n<div class=\"wp-block-kadence-spacer aligncenter kt-block-spacer-1871_8e3e11-7e\"><div class=\"kt-block-spacer kt-block-spacer-halign-center\"><hr class=\"kt-divider\"\/><\/div><\/div>\n<\/div><\/div>\n\n<\/div><\/div>\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Viinit Pirulan viinit Pirulan punainen Pirula Punainen Keskit\u00e4ytel\u00e4inen, runsaan mustaherukkainen, kevyen ruusunmarjainen, hennon mustikkainen, herukanlehtinen. Alkoholia 10,5\u202f%, 0,75 l Pirityinen Pirityinen Kuiva, hapokas, valkoherukkainen, sitruksinen, karviaismainen, hennon ginimausteinen. Alkoholia 11,0\u202f%, 0,75\u202fl Pirulan Rose Pirulan Rose Vaalean punainen, puolimakea, kyps\u00e4n valkoherukkainen, kevyen ruusunmarjainen, hennon mustaherukkainen, herukanlehtinen. Alkoholia 10,0 %, 0,75 l Pirula valkoinen Pirulan Valkoinen Kullankeltainen,&#8230;<\/p>","protected":false},"author":1,"featured_media":1485,"parent":898,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_kad_blocks_custom_css":"","_kad_blocks_head_custom_js":"","_kad_blocks_body_custom_js":"","_kad_blocks_footer_custom_js":"","_kadence_starter_templates_imported_post":false,"_kad_post_transparent":"","_kad_post_title":"","_kad_post_layout":"","_kad_post_sidebar_id":"","_kad_post_content_style":"","_kad_post_vertical_padding":"","_kad_post_feature":"","_kad_post_feature_position":"","_kad_post_header":false,"_kad_post_footer":false,"_kad_post_classname":"","footnotes":""},"class_list":["post-1871","page","type-page","status-publish","has-post-thumbnail","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Viinit - pirula - ylistaro<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.pirula.fi\/en\/tuotteet\/viinit\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Viinit - pirula - ylistaro\" \/>\n<meta property=\"og:description\" content=\"Viinit Pirulan viinit Pirulan punainen Pirula Punainen Keskit\u00e4ytel\u00e4inen, runsaan mustaherukkainen, kevyen ruusunmarjainen, hennon mustikkainen, herukanlehtinen. Alkoholia 10,5\u202f%, 0,75 l Pirityinen Pirityinen Kuiva, hapokas, valkoherukkainen, sitruksinen, karviaismainen, hennon ginimausteinen. Alkoholia 11,0\u202f%, 0,75\u202fl Pirulan Rose Pirulan Rose Vaalean punainen, puolimakea, kyps\u00e4n valkoherukkainen, kevyen ruusunmarjainen, hennon mustaherukkainen, herukanlehtinen. Alkoholia 10,0 %, 0,75 l Pirula valkoinen Pirulan Valkoinen Kullankeltainen,...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.pirula.fi\/en\/tuotteet\/viinit\/\" \/>\n<meta property=\"og:site_name\" content=\"pirula - ylistaro\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/pirula.fi\" \/>\n<meta property=\"article:modified_time\" content=\"2026-06-27T07:19:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2023\/06\/Pirulan-kyltti.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1500\" \/>\n\t<meta property=\"og:image:height\" content=\"2170\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/viinit\\\/\",\"url\":\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/viinit\\\/\",\"name\":\"Viinit - pirula - ylistaro\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/viinit\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/viinit\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.pirula.fi\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Pirulan-kyltti.jpg\",\"datePublished\":\"2026-06-27T07:19:08+00:00\",\"dateModified\":\"2026-06-27T07:19:49+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/viinit\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/viinit\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/viinit\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.pirula.fi\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Pirulan-kyltti.jpg\",\"contentUrl\":\"https:\\\/\\\/www.pirula.fi\\\/2023\\\/wp-content\\\/uploads\\\/2023\\\/06\\\/Pirulan-kyltti.jpg\",\"width\":1500,\"height\":2170},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/viinit\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Etusivu\",\"item\":\"https:\\\/\\\/www.pirula.fi\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tuotteet\",\"item\":\"https:\\\/\\\/www.pirula.fi\\\/tuotteet\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Viinit\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/#website\",\"url\":\"https:\\\/\\\/www.pirula.fi\\\/\",\"name\":\"pirula - ylistaro\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.pirula.fi\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/#organization\",\"name\":\"pirula - ylistaro\",\"url\":\"https:\\\/\\\/www.pirula.fi\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.pirula.fi\\\/2023\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Pirula-logo-etiketti-valkoinen.png\",\"contentUrl\":\"https:\\\/\\\/www.pirula.fi\\\/2023\\\/wp-content\\\/uploads\\\/2026\\\/05\\\/cropped-Pirula-logo-etiketti-valkoinen.png\",\"width\":1569,\"height\":457,\"caption\":\"pirula - ylistaro\"},\"image\":{\"@id\":\"https:\\\/\\\/www.pirula.fi\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/pirula.fi\",\"https:\\\/\\\/www.instagram.com\\\/pirulantila\\\/\",\"https:\\\/\\\/www.tiktok.com\\\/@pirulantila\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Viinit - pirula - ylistaro","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.pirula.fi\/en\/tuotteet\/viinit\/","og_locale":"en_US","og_type":"article","og_title":"Viinit - pirula - ylistaro","og_description":"Viinit Pirulan viinit Pirulan punainen Pirula Punainen Keskit\u00e4ytel\u00e4inen, runsaan mustaherukkainen, kevyen ruusunmarjainen, hennon mustikkainen, herukanlehtinen. Alkoholia 10,5\u202f%, 0,75 l Pirityinen Pirityinen Kuiva, hapokas, valkoherukkainen, sitruksinen, karviaismainen, hennon ginimausteinen. Alkoholia 11,0\u202f%, 0,75\u202fl Pirulan Rose Pirulan Rose Vaalean punainen, puolimakea, kyps\u00e4n valkoherukkainen, kevyen ruusunmarjainen, hennon mustaherukkainen, herukanlehtinen. Alkoholia 10,0 %, 0,75 l Pirula valkoinen Pirulan Valkoinen Kullankeltainen,...","og_url":"https:\/\/www.pirula.fi\/en\/tuotteet\/viinit\/","og_site_name":"pirula - ylistaro","article_publisher":"https:\/\/www.facebook.com\/pirula.fi","article_modified_time":"2026-06-27T07:19:49+00:00","og_image":[{"width":1500,"height":2170,"url":"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2023\/06\/Pirulan-kyltti.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.pirula.fi\/tuotteet\/viinit\/","url":"https:\/\/www.pirula.fi\/tuotteet\/viinit\/","name":"Viinit - pirula - ylistaro","isPartOf":{"@id":"https:\/\/www.pirula.fi\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.pirula.fi\/tuotteet\/viinit\/#primaryimage"},"image":{"@id":"https:\/\/www.pirula.fi\/tuotteet\/viinit\/#primaryimage"},"thumbnailUrl":"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2023\/06\/Pirulan-kyltti.jpg","datePublished":"2026-06-27T07:19:08+00:00","dateModified":"2026-06-27T07:19:49+00:00","breadcrumb":{"@id":"https:\/\/www.pirula.fi\/tuotteet\/viinit\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.pirula.fi\/tuotteet\/viinit\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pirula.fi\/tuotteet\/viinit\/#primaryimage","url":"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2023\/06\/Pirulan-kyltti.jpg","contentUrl":"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2023\/06\/Pirulan-kyltti.jpg","width":1500,"height":2170},{"@type":"BreadcrumbList","@id":"https:\/\/www.pirula.fi\/tuotteet\/viinit\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Etusivu","item":"https:\/\/www.pirula.fi\/"},{"@type":"ListItem","position":2,"name":"Tuotteet","item":"https:\/\/www.pirula.fi\/tuotteet\/"},{"@type":"ListItem","position":3,"name":"Viinit"}]},{"@type":"WebSite","@id":"https:\/\/www.pirula.fi\/#website","url":"https:\/\/www.pirula.fi\/","name":"pirula - ylistaro","description":"","publisher":{"@id":"https:\/\/www.pirula.fi\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.pirula.fi\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.pirula.fi\/#organization","name":"pirula - ylistaro","url":"https:\/\/www.pirula.fi\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.pirula.fi\/#\/schema\/logo\/image\/","url":"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/cropped-Pirula-logo-etiketti-valkoinen.png","contentUrl":"https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2026\/05\/cropped-Pirula-logo-etiketti-valkoinen.png","width":1569,"height":457,"caption":"pirula - ylistaro"},"image":{"@id":"https:\/\/www.pirula.fi\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/pirula.fi","https:\/\/www.instagram.com\/pirulantila\/","https:\/\/www.tiktok.com\/@pirulantila"]}]}},"taxonomy_info":[],"featured_image_src_large":["https:\/\/www.pirula.fi\/2023\/wp-content\/uploads\/2023\/06\/Pirulan-kyltti-708x1024.jpg",708,1024,true],"author_info":{"display_name":"Pirula Oy","author_link":"https:\/\/www.pirula.fi\/en\/author\/pirula11122022\/"},"comment_info":0,"_links":{"self":[{"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/pages\/1871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/comments?post=1871"}],"version-history":[{"count":3,"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/pages\/1871\/revisions"}],"predecessor-version":[{"id":1877,"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/pages\/1871\/revisions\/1877"}],"up":[{"embeddable":true,"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/pages\/898"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/media\/1485"}],"wp:attachment":[{"href":"https:\/\/www.pirula.fi\/en\/wp-json\/wp\/v2\/media?parent=1871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}